{"id":17259,"date":"2023-12-07T12:00:10","date_gmt":"2023-12-07T11:00:10","guid":{"rendered":"https:\/\/www.juridicus.de\/blog\/?p=17259"},"modified":"2023-12-21T14:29:46","modified_gmt":"2023-12-21T13:29:46","slug":"protokoll-der-muendlichen-pruefung-zum-2-staatsexamen-berlin-vom-november-2023","status":"publish","type":"post","link":"https:\/\/www.juridicus.de\/blog\/protokoll-der-muendlichen-pruefung-zum-2-staatsexamen-berlin-vom-november-2023\/","title":{"rendered":"Protokoll der m\u00fcndlichen Pr\u00fcfung zum 2. Staatsexamen &#8211; Berlin vom November 2023"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text]\n<h2>Pr\u00fcfungsthemen: \u00d6ffentliches Recht<\/h2>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<h2>Vorpunkte der Kandidaten<\/h2>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<table style=\"width: 259px;\" width=\"265\">\n<tbody>\n<tr>\n<td style=\"width: 175.052px;\">\n<p style=\"text-align: left;\">Kandidat<\/p>\n<\/td>\n<td style=\"width: 69.9826px;\">\n<p style=\"text-align: center;\">1<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 175.052px;\">\n<p style=\"text-align: left;\">Endpunkte<\/p>\n<\/td>\n<td style=\"width: 69.9826px;\">\n<p style=\"text-align: center;\">11,26<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 175.052px;\">\n<p style=\"text-align: left;\">Endnote<\/p>\n<\/td>\n<td style=\"width: 69.9826px;\">\n<p style=\"text-align: center;\">12,18<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 175.052px;\">\n<p style=\"text-align: left;\">Endnote 1. Examen<\/p>\n<\/td>\n<td style=\"width: 69.9826px;\">\n<p style=\"text-align: center;\">9,63<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<h2 style=\"text-align: justify;\">Zur Sache:<\/h2>\n<p style=\"text-align: justify;\"><strong>Pr\u00fcfungsthemen: A<\/strong>ktuelle politische Themen, Stra\u00dfenverkehrsrecht, Vereinsverbot<\/p>\n<p style=\"text-align: justify;\"><strong>Paragraphen:<\/strong> <a href=\"https:\/\/dejure.org\/gesetze\/GG\/72.html\">\u00a745 StVO, \u00a73 VereinsG, \u00a79 GG, \u00a76<\/a><a href=\"https:\/\/dejure.org\/gesetze\/GG\/72.html\">3 VereinsG, \u00a750 VwGO<\/a><\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"line-height: 1.5;\">Pr\u00fcfungsgespr\u00e4ch: <\/span><\/strong><span style=\"line-height: 1.5;\">Frage-Antwort<\/span>, h\u00e4lt Reihenfolge ein, halt am Fall<\/p>\n[\/vc_column_text][vc_column_text]\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text]\n<h2 style=\"text-align: justify;\">Pr\u00fcfungsgespr\u00e4ch:<\/h2>\n<p style=\"text-align: justify;\">Der Pr\u00fcfer stieg mit einzelnen, kleinen Fragen in die Pr\u00fcfung ein. Diese standen in keinem Zusammenhang, au\u00dfer dass sie an Themen der vorangegangenen Pr\u00fcfungen ankn\u00fcpften. Beispielsweise fragte er an den Strafrechtsfall angelehnt, aus welchem Rechtssatz die Unschuldsvermutung folge. Hier wollte er nur die Menschenw\u00fcrde, <a href=\"https:\/\/dejure.org\/gesetze\/GG\/1.html\" target=\"_blank\" title=\"Art. 1 GG\">Art. 1 GG<\/a>, h\u00f6ren. Damit war er zufrieden und wandte sich an die n\u00e4chste Kandidatin. Einsetzende Erl\u00e4uterungen, warum das so sei, was die Menschenw\u00fcrde ist, warum die Unschuldsvermutung Teil ihrer ist, unterband er sofort. Wie sich aus den Protokollen ergibt, verfolgt er diesen Ansatz kleinerer Fragen in Anlehnung vorangegangener Pr\u00fcfungsthemen h\u00e4ufiger. Auf diese Art der Fragen und ihre Inhalte kann man sich nicht vorbereiten. Man sollte daher nur wissen, dass es diesen Pr\u00fcfungseinstieg gibt, und darf davon nicht \u00fcberrascht sein, sondern muss spontan reagieren k\u00f6nnen. Nach den Einstiegsfragen wollte der Pr\u00fcfer wissen, welches politische Thema uns einfiele, mit welchem die Bundesinnenministerien zuletzt in den Medien pr\u00e4sent war. Reihum musste jeder ein Thema nennen, bis bei der f\u00fcnften Antwort das Thema genannt wurde, auf das er hinauswollte (Vereinsverbote). Wenn andere Themen als Antwort genannt wurden, nahm er das aber gleichwohl positiv auf, lobte sogar ausdr\u00fccklich, dass das ein spannendes Thema sei, welches er unbedingt mal zum Pr\u00fcfungsgegenstand machen sollte. Wenn jedoch Themen genannt wurden, die f\u00fcr ihn nicht hinreichend aktuell waren, kritisierte er allerdings die Antwort als alten, irrelevanten Hut. Zum Thema Vereinsverbote stellte er anschlie\u00dfend allgemein politische, nicht juristische Fragen wie aus welchen Szenen die verbotenen Vereine stammten. Insgesamt war also kein Detailwissen verlangt. Mehrere Minuten lang wurden auch keine juristischen Fragen gestellt. Der Pr\u00fcfer wollte vielmehr abchecken, ob wir politisch interessierte Menschen sind, die die tagesaktuellen Themen verfolgen und sich wenigstens oberfl\u00e4chlich in ihnen politisch auskennen. Erst jetzt begann die eigentliche \u201ejuristische Pr\u00fcfung\u201c, die er geplant hatte. Die gesamte \u201ejuristische Pr\u00fcfung\u201c besch\u00e4ftigte sich ausschlie\u00dflich mit Fragen zum Verwaltungsakt (die Arten von Verwaltungsakten, beh\u00f6rdliche Zust\u00e4ndigkeiten, das Verh\u00e4ltnis verschiedener Verwaltungsakte) und zur Zul\u00e4ssigkeit (gerichtliche Zust\u00e4ndigkeiten, Klageart, Klagebefugnis, Vorverfahren). Reihum fragte der Pr\u00fcfer nun Fragen zum Vereinsverbot: &#8211; Ein Vereinsverbot beruht auf welcher Rechtsgrundlage? <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7 3 I 1 VereinsG<\/a> &#8211; Was f\u00fcr eine Art von Verwaltungsakt ist das Vereinsverbot? Feststellend oder gestaltend? Das Vereinsverbot nach <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7 3 I 1 VereinsG<\/a> selbst ist ein feststellender VA, der jedoch zumeist mit einer Leistungsverf\u00fcgung gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7 3 I 2 VereinsG<\/a> verbunden wird. &#8211; Wie ist das Verh\u00e4ltnis von <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7 3 I 1 VereinsG<\/a> und <a href=\"https:\/\/dejure.org\/gesetze\/GG\/9.html\" target=\"_blank\" title=\"Art. 9 GG\">Art. 9 II GG<\/a>? Wie kann es eine solche Erm\u00e4chtigungsgrundlage im einfachen Recht geben, wenn das Grundgesetzt selbst den Verein schon f\u00fcr verboten erkl\u00e4rt (Wortlaut: \u201esind verboten\u201c)? Aus Gr\u00fcnden der Rechtssicherheit und der Rechtsklarheit (<a href=\"https:\/\/dejure.org\/gesetze\/GG\/20.html\" target=\"_blank\" title=\"Art. 20 GG\">Art. 20 Abs. 3 GG<\/a>) ist eine konstitutive Entscheidung einer zust\u00e4ndigen Beh\u00f6rde zur Feststellung des Verbots im Einzelfall erforderlich. Die <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7\u00a7 3 ff. VereinsG<\/a> gestalten das in <a href=\"https:\/\/dejure.org\/gesetze\/GG\/9.html\" target=\"_blank\" title=\"Art. 9 GG\">Art. 9 Abs. 2 GG<\/a> vorgesehene Vereinsverbot aus, welches die insoweit zust\u00e4ndige Beh\u00f6rde durch Verf\u00fcgung feststellen muss. &#8211; Mit was f\u00fcr einer Klage muss man sich vor welchem Gericht gegen ein Vereinsverbot wehren? Anfechtungsklage, <a href=\"https:\/\/dejure.org\/gesetze\/VwGO\/42.html\" target=\"_blank\" title=\"&sect; 42 VwGO [Anfechtungs- und Verpflichtungsklage, Klagebefugnis]\">\u00a7 42 I Alt. 1 VwGO<\/a> (zitiert genau bei ihm!), vor dem Bundesverwaltungsgericht gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/VwGO\/50.html\" target=\"_blank\" title=\"&sect; 50 VwGO [Zust&auml;ndigkeit des Bundesverwaltungsgerichts in erster Instanz]\">\u00a7 50 I Nr. 2 VwGO<\/a> &#8211; Ist ein Vorverfahren erforderlich? Nein, gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/VwGO\/68.html\" target=\"_blank\" title=\"&sect; 68 VwGO [Vorverfahren]\">\u00a7 68 I 2 Nr. 1 VwGO<\/a> nicht, denn nach <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/3.html\" target=\"_blank\" title=\"&sect; 3 VereinsG: Verbot\">\u00a7 3 II 1 Nr. 2 VereinsG<\/a> ist das Bundesinnenministerium, eine oberste Bundesbeh\u00f6rde zust\u00e4ndig &#8211; Ist das BVerwG aber auch dann noch zust\u00e4ndig, wenn man sich gegen Ma\u00dfnahmen zum Vollzug des Verbots wehrt? Nein, weil das nicht ausdr\u00fccklich vom Wortlaut des <a href=\"https:\/\/dejure.org\/gesetze\/VwGO\/50.html\" target=\"_blank\" title=\"&sect; 50 VwGO [Zust&auml;ndigkeit des Bundesverwaltungsgerichts in erster Instanz]\">\u00a7 50 VwGO<\/a> erfasst wird, gilt hier die allgemeine Zust\u00e4ndigkeit des VG nach <a href=\"https:\/\/dejure.org\/gesetze\/VwGO\/45.html\" target=\"_blank\" title=\"&sect; 45 VwGO [Sachliche Zust&auml;ndigkeit des Verwaltungsgerichts]\">\u00a7 45 VwGO<\/a> &#8211; Ma\u00dfnahmen zum Vollzug des Verbots h\u00e4ngen in ihrer Rechtm\u00e4\u00dfigkeit von der Rechtm\u00e4\u00dfigkeit des Vereinsverbots ab. Wie kann hier ein Auseinanderfallen der Entscheidungen von BVerwG und VG vermieden werden? Verfahren nach <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/6.html\" target=\"_blank\" title=\"&sect; 6 VereinsG: Anfechtung des Verbotsvollzugs\">\u00a7 6 I VereinsG<\/a> Insgesamt wurde damit ein nicht allen gel\u00e4ufiger Themenkomplex abgepr\u00fcft. Nutzt die Zeit, in der ihr nicht gefragt werdet, und scannt die Rechtsmaterie so schnell wie m\u00f6glich ab. So gibt beispielsweise <a href=\"https:\/\/dejure.org\/gesetze\/VereinsG\/6.html\" target=\"_blank\" title=\"&sect; 6 VereinsG: Anfechtung des Verbotsvollzugs\">\u00a7 6 I VereinsG<\/a> die Antwort auf eine seiner Fragen vor. Die Norm ist nicht schwer zu durchdringen. Doch man muss sofort anfangen, die Normen des Pr\u00fcfungsgegenstandes zu lesen, denn ansonsten kann man nicht auf die L\u00f6sung kommen (oder man kennt die Norm). Der n\u00e4chste Themenkomplex orientierte sich an einem kleinen Fall zum Stra\u00dfenverkehrsrecht. Dass der Pr\u00fcfer gerne Stra\u00dfenrecht pr\u00fcft, geht aus den Protokollen hervor. Stra\u00dfenverkehrsrecht scheint aber auch nicht zu vernachl\u00e4ssigen zu sein. Der Fall lautete: Ein Mann wohnt in einer Parkverbotszone. Laut Zusatzschild darf jedoch auf extra markierten Fl\u00e4chen geparkt werden. Genau vor seinem Haus befand sich stets eine solche Fl\u00e4che, auf der auf die Stra\u00dfe aufgetragene Markierungen in wei\u00dfer Farbe einen Parkplatz markierten. Dort parkte stets seine Freundin. Nach der R\u00fcckkehr aus dem Urlaub ist die wei\u00dfe Farbe entfernt, also kein Parkplatz mehr markiert. Seine Freundin kann ihn nicht mehr besuchen kommen und der Mann fragt nach seinen Rechtsschutzm\u00f6glichkeiten. Ohne Anspruch auf Vollst\u00e4ndigkeit fragte der Pr\u00fcfer: &#8211; Wie ist das Parkverbot rechtlich zu qualifizieren? Der markierte Parkplatz war kein Teil des Verwaltungsakts Parkverbotszone (inhaltliche Ausgestaltung dessen, man darf nirgendwo parken au\u00dfer hier), sondern ein danebenstehender Verwaltungsakt beruhend auf der Markierung, nicht auf dem Zusatzschild. Das nun folgende Parkverbot f\u00fcr diese Fl\u00e4che stellt eine Allgemeinverf\u00fcgung, <a href=\"https:\/\/dejure.org\/gesetze\/BVwVfG\/35.html\" target=\"_blank\" title=\"&sect; 35 BVwVfG: Begriff des Verwaltungsaktes\">\u00a7 35 S. 2 VwVfG<\/a>, dar und keine R\u00fccknahme\/Widerruf der vorigen Parkerlaubnis. Der Pr\u00fcfer glaubt nicht, dass die Beh\u00f6rde einen auf Aufhebung der letzten Regelung gerichteten Willen hat, wenn sie eine neue stra\u00dfenverkehrsrechtliche Regelung erl\u00e4sst. Hierbei ist mir unklar, was dann mit dem vorigen Verwaltungsakt Parkerlaubnis geschieht. &#8211; Auf welcher Erm\u00e4chtigungsgrundlage beruht das Parkverbot? <a href=\"https:\/\/dejure.org\/gesetze\/StVO\/45.html\" target=\"_blank\" title=\"&sect; 45 StVO: Verkehrszeichen und Verkehrseinrichtungen\">\u00a7 45 I 1 StVO<\/a> &#8211; Ab wann ist das Parkverbot wirksam? Mit Bekanntgabe gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/BVwVfG\/43.html\" target=\"_blank\" title=\"&sect; 43 BVwVfG: Wirksamkeit des Verwaltungsaktes\">\u00a7 43 I VwVfG<\/a>. Diese erfolgt durch das Abziehen der bisherigen wei\u00dfen Farbe\/Markierung. Es gibt einen Streit, ob die Bekanntgabe in dem Moment der Entfernung generell f\u00fcr jedermann erfolgt oder individuell bei pers\u00f6nlicher Kenntnisnahme der Entfernung. &#8211; Welche beh\u00f6rdlichen Zust\u00e4ndigkeiten sind herbei relevant? Die Stra\u00dfenverkehrsbeh\u00f6rde erl\u00e4sst den Verwaltungsakt Parkverbot gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/StVO\/45.html\" target=\"_blank\" title=\"&sect; 45 StVO: Verkehrszeichen und Verkehrseinrichtungen\">\u00a7 45 I 1 StVO<\/a>, aber f\u00fcr dessen Bekanntgabe durch Markierungsarbeiten auf der Stra\u00dfe ist die Tr\u00e4gerin der Stra\u00dfenbaulast gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/StVO\/45.html\" target=\"_blank\" title=\"&sect; 45 StVO: Verkehrszeichen und Verkehrseinrichtungen\">\u00a7 45 V 1 StVO<\/a> verantwortlich. Diese Erkenntnis bewegte ihn emotional offensichtlich. Er rief freudig, aber mit Blick in unsere wenig beeindruckten Gesichter auch voller Unverst\u00e4ndnis aus, ob wir denn gar nicht verstehen k\u00f6nnten, wie gro\u00dfartig und spannend es ist, dass ein und derselbe Verwaltungsakt von einer Beh\u00f6rde erlassen und dennoch von einer anderen Beh\u00f6rde bekannt gegeben werden kann. Und nein, das kann ich bis heute nicht. &#8211; Woraus folgt die Klagebefugnis? Aus der allgemeinen Handlungsfreiheit, wobei es dem Pr\u00fcfer wichtig war, dass der Mann nicht Adressat des Verwaltungsaktes ist. Dennoch schr\u00e4nkt jedes stra\u00dfenverkehrsrechtliche Verbot irgendwo in Deutschland die Handlungsfreiheit eines jeden irgendwo in Deutschland ein.<\/p>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<p style=\"text-align: justify;\">Bei den obigen anonymisierten Protokollen handelt es sich um eine Original-Mitschrift aus dem zweiten Staatsexamen der\u00a0<strong>M\u00fcndlichen Pr\u00fcfung in Berlin im November 2023<\/strong>. Das Protokoll stammt aus dem Fundus des Protokollverleihs\u00a0<a href=\"http:\/\/www.juridicus.de\/pruefungsprotokolle\">Juridicus.de<\/a>.<\/p>\n<p style=\"text-align: justify;\">Weggelassen wurden die Angaben zum Pr\u00fcferverhalten. Die Schilderung des Falles und die L\u00f6sung beruhen ausschlie\u00dflich auf der Wahrnehmung des Pr\u00fcflings.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Pr\u00fcfungsthemen: \u00d6ffentliches Recht [\/vc_column_text][vc_column_text] Vorpunkte der Kandidaten [\/vc_column_text][vc_column_text] Kandidat 1 Endpunkte 11,26 Endnote 12,18 Endnote 1. Examen 9,63 [\/vc_column_text][vc_column_text] Zur Sache: Pr\u00fcfungsthemen: Aktuelle politische Themen, Stra\u00dfenverkehrsrecht, Vereinsverbot Paragraphen: \u00a745 StVO, \u00a73 VereinsG, \u00a79 GG, \u00a763 VereinsG, \u00a750 VwGO Pr\u00fcfungsgespr\u00e4ch: Frage-Antwort, h\u00e4lt Reihenfolge ein, halt am Fall [\/vc_column_text][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220;&#8230;<\/p>\n","protected":false},"author":1755,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2025,1711,2010,55],"tags":[],"class_list":["post-17259","post","type-post","status-publish","format-standard","hentry","category-2-staatsexamen","category-offentliches-recht-rechtsgebiet","category-protokolle","category-magazin"],"_links":{"self":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/users\/1755"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/comments?post=17259"}],"version-history":[{"count":3,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17259\/revisions"}],"predecessor-version":[{"id":17291,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17259\/revisions\/17291"}],"wp:attachment":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/media?parent=17259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/categories?post=17259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/tags?post=17259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}