{"id":17524,"date":"2024-05-22T09:00:42","date_gmt":"2024-05-22T07:00:42","guid":{"rendered":"https:\/\/www.juridicus.de\/blog\/?p=17524"},"modified":"2024-05-15T10:07:31","modified_gmt":"2024-05-15T08:07:31","slug":"gedaechtnisprotokoll-einer-echten-klausur-zum-1-staatsexamen-hessen-im-oktober-2023-2","status":"publish","type":"post","link":"https:\/\/www.juridicus.de\/blog\/gedaechtnisprotokoll-einer-echten-klausur-zum-1-staatsexamen-hessen-im-oktober-2023-2\/","title":{"rendered":"Ged\u00e4chtnisprotokoll einer echten Klausur zum 1. Staatsexamen &#8211; Hessen im Oktober 2023"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider\"><\/div>[vc_column_text]\n<h2>Pr\u00fcfungsfach:\u00a0 \u00d6ffentliches Recht<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text]\n<h2 style=\"text-align: justify;\">Ged\u00e4chtnisprotokoll:<\/h2>\n<p style=\"text-align: justify;\">Bei der Klausur \u00d6R musste eine Verfassungsbeschwerde gepr\u00fcft werden. Grob zusammengefasst wollte sich ein Soldat gegen die Pflicht zum Schneiden seiner Haare wehren. Der Fall wurzelt in der Entscheidung des BVerwG, Urteil vom 31.01.2019 &#8211; <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=1%20WB%2028.17\" target=\"_blank\" title=\"BVerwG, 31.01.2019 - 1 WB 28.17: Haar- und Barterlass bedarf gesetzlicher Erm&auml;chtigung\">1 WB 28.17<\/a> Gepr\u00fcft werden mussten die Grundrechte <a href=\"https:\/\/dejure.org\/gesetze\/GG\/5.html\" target=\"_blank\" title=\"Art. 5 GG\">Art. 5<\/a> I, <a href=\"https:\/\/dejure.org\/gesetze\/GG\/2.html\" target=\"_blank\" title=\"Art. 2 GG\">Art. 2<\/a> I i.V.m. <a href=\"https:\/\/dejure.org\/gesetze\/GG\/1.html\" target=\"_blank\" title=\"Art. 1 GG\">Art. 1 I GG<\/a> und <a href=\"https:\/\/dejure.org\/gesetze\/GG\/3.html\" target=\"_blank\" title=\"Art. 3 GG\">Art. 3 I GG<\/a>. Problematisch war bei den Schranken insbesondere, ob f\u00fcr den Haar- und Barterlass der Bundeswehr eine gesetzliche Erm\u00e4chtigung existiert bzw. existieren muss. BVerwG: F\u00fcr Haar- und Barterlass der Bundeswehr fehlt gesetzliche Erm\u00e4chtigung Der Zen\u00adtra\u00adlen Dienst\u00advor\u00adschrift (ZDv) A-2630\/1 &#8222;Das \u00e4u\u00ad\u00dfe\u00adre Er\u00adschei\u00adnungs\u00adbild der Sol\u00adda\u00adtin\u00adnen und Sol\u00adda\u00adten der Bun\u00addes\u00adwehr&#8220; fehlt eine aus\u00adrei\u00adchen\u00adde ge\u00adsetz\u00adli\u00adche Grund\u00adla\u00adge. Dies hat der Erste Wehrdienst Senat des Bun\u00addes\u00adver\u00adwal\u00adtungs\u00adge\u00adrichts mit Ur\u00adteil vom 31.01.2019 klar\u00adge\u00adstellt. F\u00fcr eine \u00dcber\u00adgangs\u00adzeit sei diese Dienst\u00advor\u00adschrift, die all\u00adge\u00admein als &#8222;Haar- und Barterlass&#8220; be\u00adkannt ist, aber auch zum Bei\u00adspiel Re\u00adge\u00adlun\u00adgen zu T\u00e4\u00adto\u00adwie\u00adrun\u00adgen und Pier\u00adcings trifft, bis zu einer ent\u00adspre\u00adchen\u00adden Neu\u00adre\u00adge\u00adlung wei\u00adter\u00adhin an\u00adzu\u00adwen\u00adden (Az.: <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=1%20WB%2028.17\" target=\"_blank\" title=\"BVerwG, 31.01.2019 - 1 WB 28.17: Haar- und Barterlass bedarf gesetzlicher Erm&auml;chtigung\">1 WB 28.17<\/a>). Stabsfeldwebel und Gothic-Fan will lange Haare tragen Dem jetzt entschiedenen Verfahren liegt die Wehrbeschwerde eines Stabsfeldwebels zugrunde, der nach eigenen Angaben ein Anh\u00e4nger der Gothic-Kultur ist und lange Haare tragen m\u00f6chte. Er h\u00e4lt die Regelung in Nr. 202 der ZDv A-2630\/1 f\u00fcr diskriminierend, nach der m\u00e4nnliche Soldaten die Haare kurz geschnitten tragen m\u00fcssen. Dieselbe Dienstvorschrift gestatte es Soldatinnen, die Haare lang und am Hinterkopf zusammengebunden zu tragen. Das Bundesministerium der Verteidigung hat der Beschwerde nicht abgeholfen. Gesetzliche Grundlage erforderlich Den Antrag des Soldaten auf Aufhebung der Dienstvorschrift hat das BVerwG im Ergebnis zur\u00fcckgewiesen. Wie bereits in einer fr\u00fcheren Entscheidung dargelegt, schlie\u00dfe es das Gleichberechtigungsgebot nicht aus, f\u00fcr Soldatinnen und Soldaten unterschiedliche Regelungen in Bezug auf die Dienstkleidung und Haartracht bei der Dienstaus\u00fcbung vorzusehen (<a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=NVwZ-RR%202014,%20767\" target=\"_blank\" title=\"BVerwG, 17.12.2013 - 1 WRB 2.12: Haar- und Barttracht; Uniform; Vorbehalt des Gesetzes; Einsch&auml;...\">NVwZ-RR 2014, 767<\/a>). Allerdings bed\u00fcrften Regelungen, die in die Freiheit des Einzelnen, seine \u00e4u\u00dfere Erscheinung individuell zu gestalten, eingreifen, einer hinreichend bestimmten gesetzlichen Grundlage. Dies folge aus der in <a href=\"https:\/\/dejure.org\/gesetze\/GG\/2.html\" target=\"_blank\" title=\"Art. 2 GG\">Art. 2 Abs. 1 GG<\/a> garantierten allgemeinen Handlungsfreiheit, die auch den Soldaten davor sch\u00fctze, ohne gesetzliche Grundlage durch dienstliche Weisung Einschr\u00e4nkungen seines pers\u00f6nlichen Erscheinungsbildes hinnehmen zu m\u00fcssen, die sich auch auf sein Aussehen au\u00dferhalb des Dienstes auswirken. Erm\u00e4chtigung in Soldatengesetz betrifft nicht Gestaltung von K\u00f6rperbestandteilen Eine solche ausreichende gesetzliche Grundlage enthalte \u2013 wie der Erste Wehrdienstsenat nunmehr festgestellt hat \u2013 <a href=\"https:\/\/dejure.org\/gesetze\/SG\/4.html\" target=\"_blank\" title=\"&sect; 4 SG: Ernennung, Dienstgradbezeichnungen, Uniform\">\u00a7 4 Abs. 3 Satz 2 SG<\/a> nicht. Die Norm erm\u00e4chtige jedenfalls in der seit 2017 geltenden Fassung nur zu Bestimmungen \u00fcber die Uniform und die Kleidungsst\u00fccke, die mit der Uniform getragen werden. Weder dem Wortlaut der Norm noch den Gesetzgebungsmaterialien sei eindeutig zu entnehmen, dass der Erlassgeber im Sachzusammenhang mit der Festlegung einer Kleiderordnung auch zu notwendig in den privaten Lebensbereich hineinwirkenden Regelungen \u00fcber die Gestaltung von K\u00f6rperbestandteilen von Soldatinnen und Soldaten erm\u00e4chtigt werde. Dienstvorschriften vorl\u00e4ufig weiter anzuwenden Da die fr\u00fcher geltende Vorschrift des <a href=\"https:\/\/dejure.org\/gesetze\/SG\/4.html\" target=\"_blank\" title=\"&sect; 4 SG: Ernennung, Dienstgradbezeichnungen, Uniform\">\u00a7 4 Abs. 3 Satz 2 SG<\/a> aber weiter ausgelegt worden sei und ein einheitliches Auftreten der Bundeswehr im Interesse ihrer Funktionsf\u00e4higkeit geboten sei, seien die Dienstvorschriften bis zu einer gesetzlichen Neuregelung vorl\u00e4ufig weiter anzuwenden. Der Gesetzgeber werde auch dar\u00fcber zu befinden haben, ob eine unterschiedliche Regelung der Haartracht von M\u00e4nnern und Frauen in der Bundeswehr k\u00fcnftig weiterhin geboten sei.<\/p>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<p style=\"text-align: justify;\">Bei den obigen Klausurprotokoll handelt es sich um das Ged\u00e4chtnisprotokoll einer <strong>echten Klausur vom Oktober 2023 im ersten Staatsexamen in Hessen.<\/strong>\u00a0Das Protokoll stammt aus dem Fundus des Protokollverleihs\u00a0<a href=\"http:\/\/www.juridicus.de\/pruefungsprotokolle\">Juridicus.de<\/a>.<\/p>\n<p style=\"text-align: justify;\">Die Schilderung des Falles und die L\u00f6sung beruhen ausschlie\u00dflich auf der Wahrnehmung des Pr\u00fcflings.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider-border\"><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Pr\u00fcfungsfach:\u00a0 \u00d6ffentliches Recht [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Ged\u00e4chtnisprotokoll: Bei der Klausur \u00d6R musste eine Verfassungsbeschwerde gepr\u00fcft werden. Grob zusammengefasst wollte sich ein Soldat gegen die Pflicht zum Schneiden seiner Haare wehren. Der Fall wurzelt in der Entscheidung des BVerwG, Urteil vom 31.01.2019 &#8211; 1 WB 28.17 Gepr\u00fcft werden mussten die Grundrechte Art&#8230;.<\/p>\n","protected":false},"author":1755,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2222,2221,1711,55],"tags":[],"class_list":["post-17524","post","type-post","status-publish","format-standard","hentry","category-1-staatsexamen-klausurprotokoll","category-klausurprotokoll","category-offentliches-recht-rechtsgebiet","category-magazin"],"_links":{"self":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/users\/1755"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/comments?post=17524"}],"version-history":[{"count":2,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17524\/revisions"}],"predecessor-version":[{"id":17526,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17524\/revisions\/17526"}],"wp:attachment":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/media?parent=17524"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/categories?post=17524"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/tags?post=17524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}