{"id":17861,"date":"2025-01-25T09:00:58","date_gmt":"2025-01-25T08:00:58","guid":{"rendered":"https:\/\/www.juridicus.de\/blog\/?p=17861"},"modified":"2025-01-16T14:05:34","modified_gmt":"2025-01-16T13:05:34","slug":"gedaechtnisprotokoll-einer-echten-klausur-zum-2-staatsexamen-saarland-im-august-2024","status":"publish","type":"post","link":"https:\/\/www.juridicus.de\/blog\/gedaechtnisprotokoll-einer-echten-klausur-zum-2-staatsexamen-saarland-im-august-2024\/","title":{"rendered":"Ged\u00e4chtnisprotokoll einer echten Klausur zum 2. Staatsexamen &#8211; Saarland im August 2024"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider\"><\/div>[vc_column_text]\n<h2>Pr\u00fcfungsfach: \u00a0Strafrecht<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text]\n<h2>Ged\u00e4chtnisprotokoll:<\/h2>\n<div>\n<div style=\"text-align: justify;\">\n<p>Es handelte sich um eine strafrechtliche Staatsanwaltsklausur, die aus mehreren Teilen bestand. Es sollte die Strafbarkeit von vier Beteiligten (darunter zwei Polizisten) gepr\u00fcft werden. Zun\u00e4chst wurde die Polizei eingeschaltet, da an einer Tankstelle eine Pr\u00fcgelei stattgefunden hat. Mehrere Personen haben einen Mann angegriffen, der daraufhin verletzt war. Schwerpunkt lag hier auf der Beweisw\u00fcrdigung (Indizienkette bzw. Indizienring). Man wusste nicht genau, wer was getan hat, aber z.B., dass ein Mann mit schwarzem Schal gegen den Kopf getreten hat und dass ein Mann mit Schal dann auf der Fahrerseite eines Autos eingestiegen ist. \u00c4hnlich war es f\u00fcr den Beifahrer. Es gab einige Zeugenaussagen. Die beiden M\u00e4nner sind dann im Wagen gefl\u00fcchtet, die Polizei hinterher. M\u00f6glichst hohe Geschwindigkeit etc., Schwerpunkt war das neue Kraftfahrzeugrennen. Anschlie\u00dfend hat das Auto gehalten, beide sind gefl\u00fcchtet. Einer der beiden konnte gestellt werden, ein anderer war verschwunden. Auch hier erneut Beweisw\u00fcrdigung anhand von Indizien, wer ist wer. Bei dem angetroffenen handelte es sich dann nach der Indizienlage um den Beifahrer, der gerade sein Handy dabeihatte und wohl eine Sprachnachricht an den Fahrer verfasste. Das Handy sollte ihm weggenommen werden, er hat sich gew\u00e4hrt, die Polizisten haben Gewalt angewendet, daher sollte auch deren Strafbarkeit gepr\u00fcft werden.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<p style=\"text-align: justify;\">Bei den obigen Klausurprotokoll handelt es sich um das Ged\u00e4chtnisprotokoll einer <strong>echten Klausur vom August 2024 im zweiten Staatsexamen im Saarland.<\/strong>\u00a0Das Protokoll stammt aus dem Fundus des Protokollverleihs <a href=\"http:\/\/www.juridicus.de\/pruefungsprotokolle\">Juridicus.de<\/a>.<\/p>\n<p style=\"text-align: justify;\">Die Schilderung des Falles und die L\u00f6sung beruhen ausschlie\u00dflich auf der Wahrnehmung des Pr\u00fcflings.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider-border\"><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Pr\u00fcfungsfach: \u00a0Strafrecht [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Ged\u00e4chtnisprotokoll: Es handelte sich um eine strafrechtliche Staatsanwaltsklausur, die aus mehreren Teilen bestand. Es sollte die Strafbarkeit von vier Beteiligten (darunter zwei Polizisten) gepr\u00fcft werden. Zun\u00e4chst wurde die Polizei eingeschaltet, da an einer Tankstelle eine Pr\u00fcgelei stattgefunden hat. Mehrere Personen haben einen Mann angegriffen, der daraufhin&#8230;<\/p>\n","protected":false},"author":1755,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2223,2221,55,1715],"tags":[],"class_list":["post-17861","post","type-post","status-publish","format-standard","hentry","category-2-staatsexamen-klausurprotokoll","category-klausurprotokoll","category-magazin","category-strafrecht-rechtsgebiet"],"_links":{"self":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/users\/1755"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/comments?post=17861"}],"version-history":[{"count":1,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17861\/revisions"}],"predecessor-version":[{"id":17862,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17861\/revisions\/17862"}],"wp:attachment":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/media?parent=17861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/categories?post=17861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/tags?post=17861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}