{"id":17940,"date":"2025-03-29T09:00:13","date_gmt":"2025-03-29T08:00:13","guid":{"rendered":"https:\/\/www.juridicus.de\/blog\/?p=17940"},"modified":"2025-03-22T12:44:36","modified_gmt":"2025-03-22T11:44:36","slug":"gedaechtnisprotokoll-einer-echten-klausur-zum-2-staatsexamen-bayern-im-juni-2024","status":"publish","type":"post","link":"https:\/\/www.juridicus.de\/blog\/gedaechtnisprotokoll-einer-echten-klausur-zum-2-staatsexamen-bayern-im-juni-2024\/","title":{"rendered":"Ged\u00e4chtnisprotokoll einer echten Klausur zum 2. Staatsexamen &#8211; Bayern im Juni 2024"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider\"><\/div>[vc_column_text]\n<h2>Pr\u00fcfungsfach: \u00a0Strafrecht<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text]\n<h2>Ged\u00e4chtnisprotokoll:<\/h2>\n<div>\n<div style=\"text-align: justify;\">\n<p>1. Hausfriedensbruch: Es wird ein Hausfriedensbruch gem\u00e4\u00df <a href=\"https:\/\/dejure.org\/gesetze\/StGB\/123.html\" target=\"_blank\" title=\"&sect; 123 StGB: Hausfriedensbruch\">\u00a7 123 StGB<\/a> durch unerlaubtes Betreten der Mietr\u00e4ume des Vermieters thematisiert. Aufgrund unklarer Tatzeiten k\u00f6nnte es Probleme mit der Frist f\u00fcr den Strafantrag geben, was zu einer Teileinstellung des Verfahrens f\u00fchren k\u00f6nnte.<br \/>\n2. Unbefugtes \u00d6ffnen eines Fahrzeugs: Der Vermieter wird beschuldigt, ein vor der Wohnung geparktes Auto der Mieterin, ohne deren Einverst\u00e4ndnis mit einem Signalverst\u00e4rker ge\u00f6ffnet zu haben. Dies geschah mit der Absicht, Druck auf die Mieterin auszu\u00fcben, um sie zum Auszug zu bewegen, trotz einer unwirksamen K\u00fcndigung. Hier wird die M\u00f6glichkeit eines besonders schweren Diebstahls sowie einer versuchten Erpressung gepr\u00fcft. 3. Zuparken und Drohung: Der Vermieter soll das Auto der Mieterin zugeparkt und unter verbaler Drohung einen Haust\u00fcrschl\u00fcssel gefordert haben. Es wird die rechtliche Einordnung als Erpressung oder N\u00f6tigung diskutiert, wobei auch die Frage der Beweisbarkeit und der Auswirkungen einer m\u00f6glichen Alkoholisierung des Beschuldigten w\u00e4hrend der polizeilichen Vernehmung angesprochen wird. Insgesamt wird die rechtliche Situation und die Beweisf\u00fchrung in diesen F\u00e4llen detailliert analysiert, wobei verschiedene rechtliche Aspekte und m\u00f6gliche Verteidigungsstrategien betrachtet werden.<\/p>\n<\/div>\n<\/div>\n[\/vc_column_text]<div  class=\"divider\"><\/div>[vc_column_text]\n<p style=\"text-align: justify;\">Bei den obigen Klausurprotokoll handelt es sich um das Ged\u00e4chtnisprotokoll einer <strong>echten Klausur vom Juni 2024 im zweiten Staatsexamen in Bayern.<\/strong>\u00a0Das Protokoll stammt aus dem Fundus des Protokollverleihs <a href=\"http:\/\/www.juridicus.de\/pruefungsprotokolle\">Juridicus.de<\/a>.<\/p>\n<p style=\"text-align: justify;\">Die Schilderung des Falles und die L\u00f6sung beruhen ausschlie\u00dflich auf der Wahrnehmung des Pr\u00fcflings.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;]<div  class=\"divider-border\"><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Pr\u00fcfungsfach: \u00a0Strafrecht [\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243;][vc_column_text] Ged\u00e4chtnisprotokoll: 1. Hausfriedensbruch: Es wird ein Hausfriedensbruch gem\u00e4\u00df \u00a7 123 StGB durch unerlaubtes Betreten der Mietr\u00e4ume des Vermieters thematisiert. Aufgrund unklarer Tatzeiten k\u00f6nnte es Probleme mit der Frist f\u00fcr den Strafantrag geben, was zu einer Teileinstellung des Verfahrens f\u00fchren k\u00f6nnte. 2. Unbefugtes \u00d6ffnen eines Fahrzeugs: Der&#8230;<\/p>\n","protected":false},"author":1755,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2223,2221,55,1715],"tags":[],"class_list":["post-17940","post","type-post","status-publish","format-standard","hentry","category-2-staatsexamen-klausurprotokoll","category-klausurprotokoll","category-magazin","category-strafrecht-rechtsgebiet"],"_links":{"self":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/users\/1755"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/comments?post=17940"}],"version-history":[{"count":1,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17940\/revisions"}],"predecessor-version":[{"id":17941,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/posts\/17940\/revisions\/17941"}],"wp:attachment":[{"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/media?parent=17940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/categories?post=17940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.juridicus.de\/blog\/wp-json\/wp\/v2\/tags?post=17940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}